{"id":26417,"date":"2020-02-21T00:00:00","date_gmt":"2020-02-21T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/"},"modified":"2020-02-21T00:00:00","modified_gmt":"2020-02-21T00:00:00","slug":"dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/","title":{"rendered":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 !"},"content":{"rendered":"<p>Soumettez une ou plusieurs candidatures d\u00e8s aujourd\u2019hui (voir la liste ci-dessous) en utilisant le <a href=\"https:\/\/licence.equestrian.ca\/ecawards\/?lang=fr\" target=\"_blank\" rel=\"noopener\">portail des Prix nationaux de CE<\/a>. C\u2019est rapide et simple d\u2019utilisation et nous acceptons les candidatures jusqu\u2019au 24 f\u00e9vrier 2020.&nbsp;<\/p>\n<\/p>\n<\/p>\n<\/p>\n<ul><\/ul>\n<p><a href=\"https:\/\/licence.equestrian.ca\/ecawards\/?lang=fr\" class=\"o-button js-wow u-fadeInUpBig\" data-wow-delay=\"0.3s\" style=\"visibility: visible; animation-delay: 0.3s; display: block; margin: 15px auto;width: 50%;\">Soumettre une candidature!<\/a><\/p>\n<\/p>\n<\/p>\n<p>L\u2019appel de candidatures est lanc\u00e9 pour les prix suivants :<\/p>\n<ul>\n<li>Prix M\u00e9daille d\u2019or<\/li>\n<li>Prix pour l\u2019ensemble des r\u00e9alisations<\/li>\n<li>Sportif \u00e9questre de l\u2019ann\u00e9e \u2013 Troph\u00e9e Dr George Jacobsen<\/li>\n<li>Sportif \u00e9questre junior de l\u2019ann\u00e9e \u2013 Troph\u00e9e Gillian Wilson<\/li>\n<li>Cheval d\u2019exception \u2013 Troph\u00e9e Hickstead<\/li>\n<li>B\u00e9n\u00e9vole de l\u2019ann\u00e9e<\/li>\n<li>Propri\u00e9taire de l\u2019ann\u00e9e<\/li>\n<li>Cheval de l\u2019ann\u00e9e <\/li>\n<li>\u00c9leveur canadien de l\u2019ann\u00e9e<\/li>\n<li>Cheval d\u2019origine canadienne de l\u2019ann\u00e9e<\/li>\n<li>Prix M\u00e9dias \u2013 Troph\u00e9e Susan Jane Anstey<\/li>\n<li>Prix Sant\u00e9 et Bien-\u00eatre <\/li>\n<\/ul>\n<p>Vous trouverez tous les crit\u00e8res de s\u00e9lection \u00e0 <a href=\"http:\/\/www.canadaequestre.ca\/infos\/prix-nationaux\" target=\"_blank\" rel=\"noopener\">www.canadaequestre.ca\/infos\/prix-nationaux<\/a>.  <\/p>\n<p>Si vous connaissez une personne, un cheval ou un organisme digne d\u2019un prix national de CE, pri\u00e8re de soumettre sa candidature <b>avant la date limite du 24 f\u00e9vrier 2020 \u00e0 16 h (HE)<\/b>.<\/p>\n<h2>Processus de s\u00e9lection des prix nationaux de CE<\/h2>\n<p>Les candidatures pour les Prix nationaux de CE seront \u00e9valu\u00e9es et, avec l\u2019appui et la contribution d\u2019intervenants et d\u2019experts de CE, le comit\u00e9 des Prix CE s\u00e9lectionnera les laur\u00e9ats. Cette ann\u00e9e, celui-ci est compos\u00e9 de Carla Robin (pr\u00e9sidente), Jennifer Anstey, Mark Goldman, Peggy Hambly et Karen Sparks.<\/p>\n<\/p>\n<\/p>\n<\/p>\n<ul><\/ul>\n<p><a href=\"https:\/\/licence.equestrian.ca\/ecawards\/?lang=fr\" class=\"o-button js-wow u-fadeInUpBig\" data-wow-delay=\"0.3s\" style=\"visibility: visible; animation-delay: 0.3s; display: block; margin: 15px auto;width: 50%;\">Soumettre une candidature!<\/a><\/p>\n<\/p>\n<\/p>\n<p>Des questions? Des commentaires?<\/p>\n<p>Questions or comments regarding the EC National Awards can be directed to:<\/p>\n<p>Pour toute question ou tout commentaire au sujet des Prix CE, veuillez vous adresser \u00e0 :<\/p>\n<p>Carla Robin<br \/>Pr\u00e9sidente du comit\u00e9 des Prix CE<br \/><a href=\"mailto:AwardsCommittee@equestrian.ca\" target=\"_blank\" rel=\"noopener\">AwardsCommittee@equestrian.ca<\/a><\/p>\n<p>Jessie Christie<br \/>Gestionnaire principale, Marketing et communications de CE<br \/><a href=\"mailto:jchristie@equestrian.ca\" target=\"_blank\" style=\"background-color: white;\" rel=\"noopener\">jchristie@equestrian.ca<\/a><\/p>\n<p style=\"text-align: center;\">&#8211; 30 &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soumettez une ou plusieurs candidatures d\u00e8s aujourd\u2019hui (voir la liste ci-dessous) en utilisant le portail des Prix nationaux de CE. C\u2019est rapide et simple d\u2019utilisation et nous acceptons les candidatures jusqu\u2019au 24 f\u00e9vrier 2020.&nbsp; Soumettre une candidature! L\u2019appel de candidatures est lanc\u00e9 pour les prix suivants : Prix M\u00e9daille d\u2019or Prix pour l\u2019ensemble des r\u00e9alisations [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[241],"tags":[],"class_list":["post-26417","post","type-post","status-publish","format-standard","hentry","category-anciens-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"Soumettez une ou plusieurs candidatures d\u00e8s aujourd\u2019hui (voir la liste ci-dessous) en utilisant le portail des Prix nationaux de CE. C\u2019est rapide et simple d\u2019utilisation et nous acceptons les candidatures jusqu\u2019au 24 f\u00e9vrier 2020.&nbsp; Soumettre une candidature! L\u2019appel de candidatures est lanc\u00e9 pour les prix suivants : Prix M\u00e9daille d\u2019or Prix pour l\u2019ensemble des r\u00e9alisations [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-21T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 !\",\"datePublished\":\"2020-02-21T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/\"},\"wordCount\":318,\"commentCount\":0,\"articleSection\":[\"Anciens articles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/\",\"name\":\"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\"},\"datePublished\":\"2020-02-21T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/author\\\/mberry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/","og_locale":"fr_CA","og_type":"article","og_title":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada","og_description":"Soumettez une ou plusieurs candidatures d\u00e8s aujourd\u2019hui (voir la liste ci-dessous) en utilisant le portail des Prix nationaux de CE. C\u2019est rapide et simple d\u2019utilisation et nous acceptons les candidatures jusqu\u2019au 24 f\u00e9vrier 2020.&nbsp; Soumettre une candidature! L\u2019appel de candidatures est lanc\u00e9 pour les prix suivants : Prix M\u00e9daille d\u2019or Prix pour l\u2019ensemble des r\u00e9alisations [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/","og_site_name":"Equestrian Canada","article_published_time":"2020-02-21T00:00:00+00:00","author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 !","datePublished":"2020-02-21T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/"},"wordCount":318,"commentCount":0,"articleSection":["Anciens articles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/","url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/","name":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 ! - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"datePublished":"2020-02-21T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/dernier-rappel-presentez-des-candidatures-aux-prix-nationaux-de-ce-avant-le-24-fevrier-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Dernier rappel : Pr\u00e9sentez des candidatures aux Prix nationaux de CE avant le 24 f\u00e9vrier 2020 !"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=26417"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26417\/revisions"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=26417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=26417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=26417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}