{"id":26414,"date":"2019-08-06T00:00:00","date_gmt":"2019-08-06T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/"},"modified":"2019-08-06T00:00:00","modified_gmt":"2019-08-06T00:00:00","slug":"flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/","title":{"rendered":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019"},"content":{"rendered":"<p><b>Lima, (P\u00e9rou), le 6 ao\u00fbt 2019 \u2013<\/b> \u00c0 l\u2019occasion de la premi\u00e8re comp\u00e9tition individuelle et d\u2019\u00e9quipe du saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019, le mardi 6 ao\u00fbt 2019, Lisa Carlsen, membre de l\u2019\u00e9quipe canadienne de saut d\u2019obstacles, a compl\u00e9t\u00e9 une ronde parfaite sur Parette, mais elle a plus tard \u00e9t\u00e9 \u00e9limin\u00e9e en vertu de l\u2019article 241.3.30 des R\u00e8glements du saut d\u2019obstacles de la FEI.<\/p>\n<p>Une \u00e9limination conform\u00e9ment \u00e0 l\u2019Article 241.3.30 n\u2019implique pas une intention de blesser le cheval, mais il est essentiel que ces r\u00e8glements soient appliqu\u00e9s pour garantir la protection du bien-\u00eatre des chevaux.<\/p>\n<p>\u00ab Mon cheval a eu un petit frottement aujourd\u2019hui et quand les commissaires l\u2019ont examin\u00e9 dans le cadre de la v\u00e9rification apr\u00e8s la ronde, ils ont pris la d\u00e9cision de nous \u00e9liminer, explique Carlsen. Le bien-\u00eatre de mon cheval est ma grande priorit\u00e9 et je ne ferais jamais rien pour remettre cela en question. Les r\u00e8gles sont les r\u00e8gles, mais je ne blesserais jamais mon cheval intentionnellement. Parette a \u00e9t\u00e9 attentivement v\u00e9rifi\u00e9e et elle a obtenu le feu vert des v\u00e9t\u00e9rinaires pour participer \u00e0 la comp\u00e9tition demain et je suis impatiente de continuer \u00e0 faire du mieux que l\u2019on peut pour l\u2019\u00e9quipe. Je remercie toute notre \u00e9quipe, notamment Mark Laskin, Jon Garner et le Dr Eduardo Felix pour leur soutien aujourd\u2019hui. \u00bb<\/p>\n<p>Bien que Carlsen soit \u00e9limin\u00e9e de la comp\u00e9tition individuelle \u00e0 Lima 2019, elle poursuivra la comp\u00e9tition par \u00e9quipe \u00e0 l\u2019occasion de la finale disput\u00e9e le 7 ao\u00fbt 2019.<\/p>\n<p>Pour obtenir un compl\u00e9ment d\u2019information en ce qui a trait aux \u00e9preuves \u00e9questres des Jeux panam\u00e9ricains Lima 2019, notamment l\u2019horaire complet des \u00e9preuves, de m\u00eame que le nom des participants avec leurs r\u00e9sultats, veuillez visiter le <a href=\"www.lima2019.pe\/en\" target=\"_blank\" rel=\"noopener\">www.lima2019.pe\/en<\/a>. Les r\u00e9sultats en temps r\u00e9el se trouvent <a href=\"https:\/\/online.equipe.com\/en\/competitions\/32361\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima, (P\u00e9rou), le 6 ao\u00fbt 2019 \u2013 \u00c0 l\u2019occasion de la premi\u00e8re comp\u00e9tition individuelle et d\u2019\u00e9quipe du saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019, le mardi 6 ao\u00fbt 2019, Lisa Carlsen, membre de l\u2019\u00e9quipe canadienne de saut d\u2019obstacles, a compl\u00e9t\u00e9 une ronde parfaite sur Parette, mais elle a plus tard \u00e9t\u00e9 \u00e9limin\u00e9e en vertu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[241],"tags":[],"class_list":["post-26414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anciens-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"Lima, (P\u00e9rou), le 6 ao\u00fbt 2019 \u2013 \u00c0 l\u2019occasion de la premi\u00e8re comp\u00e9tition individuelle et d\u2019\u00e9quipe du saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019, le mardi 6 ao\u00fbt 2019, Lisa Carlsen, membre de l\u2019\u00e9quipe canadienne de saut d\u2019obstacles, a compl\u00e9t\u00e9 une ronde parfaite sur Parette, mais elle a plus tard \u00e9t\u00e9 \u00e9limin\u00e9e en vertu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019\",\"datePublished\":\"2019-08-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/\"},\"wordCount\":348,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"articleSection\":[\"Anciens articles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/\",\"name\":\"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"datePublished\":\"2019-08-06T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"contentUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"width\":800,\"height\":618},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/author\\\/mberry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/","og_locale":"fr_CA","og_type":"article","og_title":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada","og_description":"Lima, (P\u00e9rou), le 6 ao\u00fbt 2019 \u2013 \u00c0 l\u2019occasion de la premi\u00e8re comp\u00e9tition individuelle et d\u2019\u00e9quipe du saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019, le mardi 6 ao\u00fbt 2019, Lisa Carlsen, membre de l\u2019\u00e9quipe canadienne de saut d\u2019obstacles, a compl\u00e9t\u00e9 une ronde parfaite sur Parette, mais elle a plus tard \u00e9t\u00e9 \u00e9limin\u00e9e en vertu [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/","og_site_name":"Equestrian Canada","article_published_time":"2019-08-06T00:00:00+00:00","og_image":[{"width":800,"height":618,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019","datePublished":"2019-08-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/"},"wordCount":348,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","articleSection":["Anciens articles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/","url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/","name":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019 - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","datePublished":"2019-08-06T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","width":800,"height":618},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/flash-info-declaration-de-canada-equestre-relativement-a-lequipe-canadienne-de-saut-dobstacles-aux-jeux-panamericains-de-lima-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Flash info : D\u00e9claration de Canada \u00c9questre relativement \u00e0 l\u2019\u00e9quipe canadienne de saut d\u2019obstacles aux Jeux panam\u00e9ricains de Lima 2019"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=26414"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3404"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=26414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=26414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=26414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}