{"id":26100,"date":"2019-04-08T00:00:00","date_gmt":"2019-04-08T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/"},"modified":"2019-04-08T00:00:00","modified_gmt":"2019-04-08T00:00:00","slug":"devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/","title":{"rendered":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018"},"content":{"rendered":"<p>Pour de plus amples renseignements, veuillez cliquer sur le nom des laur\u00e9ats :<\/p>\n<p>Athl\u00e8te de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage<\/p>\n<p><a href=\"https:\/\/www.equestrian.ca\/cdn\/storage\/resources_v2\/EDb2AqdD8rw846ypW\/original\/EDb2AqdD8rw846ypW.pdf\" target=\"_blank\" rel=\"noopener\">Sharon Buffitt<\/a><\/p>\n<p>Entra\u00eeneure de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage<\/p>\n<p><a href=\"https:\/\/www.equestrian.ca\/cdn\/storage\/resources_v2\/WTWXmn4j7p2yQJfb9\/original\/WTWXmn4j7p2yQJfb9.pdf\" target=\"_blank\" rel=\"noopener\">Karen Pavicic<\/a><\/p>\n<p>Athl\u00e8te de haute performance de l\u2019ann\u00e9e en paradressage<\/p>\n<p><a href=\"https:\/\/www.equestrian.ca\/cdn\/storage\/resources_v2\/dF3SxibG4BB48XR3p\/original\/dF3SxibG4BB48XR3p.pdf\" target=\"_blank\" rel=\"noopener\">Winona Hartvikson<\/a><\/p>\n<p>Cheval de l\u2019ann\u00e9e en paradressage<\/p>\n<p class=\"\"><a href=\"https:\/\/www.equestrian.ca\/cdn\/storage\/resources_v2\/vzJogNuGBYZh9FdGy\/original\/vzJogNuGBYZh9FdGy.pdf\" target=\"_blank\" rel=\"noopener\">Fancianna<\/a><\/p>\n<p>Prix Sandy Mitchell de Propri\u00e9taire de l\u2019ann\u00e9e en paradressage<\/p>\n<p><a href=\"https:\/\/www.equestrian.ca\/cdn\/storage\/resources_v2\/aZvYaL9PA2YyuFCPs\/original\/aZvYaL9PA2YyuFCPs.pdf\" target=\"_blank\" rel=\"noopener\">Jane Macdonald<\/a><\/p>\n<p><b>\u00c0 propos des prix de paradressage<br \/><\/b>Le Comit\u00e9 de paradressage de CE d\u00e9cerne plusieurs prix \u00e0 la communaut\u00e9 de paradressage afin de reconna\u00eetre les athl\u00e8tes, propri\u00e9taires, chevaux, b\u00e9n\u00e9voles et autres intervenants exceptionnels. Pour en apprendre plus \u00e0 propos du programme de prix en paradressage et pour consulter une liste des anciens laur\u00e9ats, visitez la page <a href=\"https:\/\/www.equestrian.ca\/sport-fr\/paradressage\/prix\" target=\"_blank\" rel=\"noopener\">www.equestrian.ca\/sport-fr\/paradressage\/prix<\/a>.<\/p>\n<p style=\"text-align: center;\">&#8211; 30 &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour de plus amples renseignements, veuillez cliquer sur le nom des laur\u00e9ats : Athl\u00e8te de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Sharon Buffitt Entra\u00eeneure de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Karen Pavicic Athl\u00e8te de haute performance de l\u2019ann\u00e9e en paradressage Winona Hartvikson Cheval de l\u2019ann\u00e9e en paradressage Fancianna Prix Sandy Mitchell de Propri\u00e9taire de l\u2019ann\u00e9e en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[241],"tags":[],"class_list":["post-26100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anciens-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"Pour de plus amples renseignements, veuillez cliquer sur le nom des laur\u00e9ats : Athl\u00e8te de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Sharon Buffitt Entra\u00eeneure de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Karen Pavicic Athl\u00e8te de haute performance de l\u2019ann\u00e9e en paradressage Winona Hartvikson Cheval de l\u2019ann\u00e9e en paradressage Fancianna Prix Sandy Mitchell de Propri\u00e9taire de l\u2019ann\u00e9e en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-08T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018\",\"datePublished\":\"2019-04-08T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\"},\"wordCount\":154,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\",\"articleSection\":[\"Anciens articles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\",\"url\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\",\"name\":\"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\",\"datePublished\":\"2019-04-08T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage\",\"url\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\",\"contentUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\",\"width\":800,\"height\":618},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/equestrian.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#website\",\"url\":\"https:\/\/equestrian.ca\/fr\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/equestrian.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\/\/equestrian.ca\/fr\/author\/mberry\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/","og_locale":"fr_CA","og_type":"article","og_title":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada","og_description":"Pour de plus amples renseignements, veuillez cliquer sur le nom des laur\u00e9ats : Athl\u00e8te de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Sharon Buffitt Entra\u00eeneure de d\u00e9veloppement de l\u2019ann\u00e9e en paradressage Karen Pavicic Athl\u00e8te de haute performance de l\u2019ann\u00e9e en paradressage Winona Hartvikson Cheval de l\u2019ann\u00e9e en paradressage Fancianna Prix Sandy Mitchell de Propri\u00e9taire de l\u2019ann\u00e9e en [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/","og_site_name":"Equestrian Canada","article_published_time":"2019-04-08T00:00:00+00:00","og_image":[{"width":800,"height":618,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018","datePublished":"2019-04-08T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/"},"wordCount":154,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","articleSection":["Anciens articles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/","url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/","name":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018 - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","datePublished":"2019-04-08T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","width":800,"height":618},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/devoilement-des-laureats-des-prix-de-fin-dannee-en-paradressage-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9voilement des laur\u00e9ats des Prix de fin d\u2019ann\u00e9e en paradressage 2018"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=26100"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/26100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3404"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=26100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=26100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=26100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}