{"id":25919,"date":"2023-04-26T00:00:00","date_gmt":"2023-04-26T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/"},"modified":"2023-04-26T00:00:00","modified_gmt":"2023-04-26T00:00:00","slug":"faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/","title":{"rendered":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique"},"content":{"rendered":"<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/ConcoursComplet.jpg' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/>Une deuxi\u00e8me place pour Kendal Lehari au CCI 4*-S d\u2019Ocala<\/p>\n<p>Le concours complet Ocala International Festival of Eventing pr\u00e9sentait une division CCI4*-S pour la toute premi\u00e8re fois depuis ses d\u00e9buts en 2006. Ce grand rendez-vous, qui a eu lieu du 20 au 23 avril 2023 au Florida Horse Park d\u2019Ocala, en Floride, a attir\u00e9 500 participants et participantes de douze pays dans les quatre divisions FEI (F\u00e9d\u00e9ration Equestre Internationale) offertes.  <\/p>\n<p><i><u>CCI 4*-S<\/u><\/i><\/p>\n<p>Kendal Lehari (Uxbridge, Ont.), qui venait d\u2019inscrire le 30 mars dernier son meilleur r\u00e9sultat \u00e0 vie lors du quatre-\u00e9toiles abr\u00e9g\u00e9 du concours complet Event at TerraNova, aux commandes de sa propre monture, Audacious (Iron Man x Meagan\u2019s Mayflower), s\u2019est encore distingu\u00e9e \u00e0 ce niveau en prenant la deuxi\u00e8me place parmi les 20 couples partants. Cette fois, elle montait Junior, un Cheval de sport canadien de 10 ans qu\u2019elle d\u00e9tient en copropri\u00e9t\u00e9 avec Gwen et Rein Lehari. Au terme de la phase initiale de dressage, elle a re\u00e7u un r\u00e9sultat de 37,5, \u00e9quivalant \u00e0 la 15e place.<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/><\/p>\n<p><i>Kendal Lehari et Audacious (aka \u201cJunior\u201d)<br \/><b>Source <\/b>: Xpress Foto<\/i><\/p>\n<p>Apr\u00e8s une seule barre d\u00e9log\u00e9e en saut d\u2019obstacles, l\u2019athl\u00e8te de 36 ans est remont\u00e9e \u00e0 la 10e position (41,5). Puis, Kendal et Junior ont franchi une option d\u00e8s le d\u00e9but de la phase de cross-country. Ce couple a \u00e9t\u00e9 le seul \u00e0 r\u00e9ussir un double sans-faute au terme du franchissement de ce trac\u00e9 tr\u00e8s technique r\u00e9alis\u00e9 par le Canadien Jay Hambly. Cet impeccable effort en cross-country leur a permis d\u2019optimiser leur meilleur r\u00e9sultat \u00e0 vie dans un 4*-S, soit 41,5, et de terminer derri\u00e8re le couple am\u00e9ricain Sharon White et Claus 36 (35,5).&nbsp;<\/p>\n<p>Sa compatriote Jessica Phoenix (Cannington, Ont.) a pris la cinqui\u00e8me place, sur la selle de Freedom GS (Humble GS x Fidertanz), la jument trakehner de 11 ans de Charlotte Schickedanz. L\u2019athl\u00e8te olympique \u00e0 trois reprises a d\u2019abord obtenu un r\u00e9sultat de 38,2 en dressage. A cette \u00e9tape, elle \u00e9tait \u00e0 un \u00e9chelon plus bas que Kendal Lehari. Elle est ensuite remont\u00e9e d\u2019un cran (11e ) apr\u00e8s avoir heurt\u00e9 une barre en saut d\u2019obstacles. Au terme du cross-country, la cavali\u00e8re de 40 ans et sa jument affichaient 42,2, un r\u00e9sultat auquel s\u2019est ajout\u00e9 une petite p\u00e9nalit\u00e9 de temps de 1,6, pour un r\u00e9sultat final de 43,8.<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Jessica-Phoenix-and-Freedom-GS-by-Xpress-Foto.jpg' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/><\/p>\n<p><i>Jessica Phoenix et Freedom GS<br \/><b>Source <\/b>: Xpress Foto<\/i><\/p>\n<p><i>Autre r\u00e9sultats canadiens notables au CCI 4*-S<\/i><\/p>\n<p>Apr\u00e8s avoir rejoint le top trois lors du CCI3*-S d\u2019Event at TerraNova, Melissa Boutin (Ascot Corner, Qc) s\u2019est dite tr\u00e8s fi\u00e8re de sa jument trakehner de 11 ans, Obeah Dancer GS (Humble GS x Buddenbrock), qui est pass\u00e9e \u00e0 la division quatre-\u00e9toiles avec brio. Le couple s\u2019est install\u00e9 au sixi\u00e8me rang avec un r\u00e9sultat de 46,4.<\/p>\n<p>Dana Cooke (Merrittville, C.-B.), qui vit actuellement en Caroline du Nord, et Quatro (Quaterstern x Coriograph B), German Sport Horse de neuf ans de Kingfisher Park, ont pris la septi\u00e8me position avec un r\u00e9sultat de 47,7.<\/p>\n<p>Kyle Carter (Calgary, Alb.), qui vit actuellement en Floride, \u00e9tait \u00e0 bord du cheval le plus \u00e2g\u00e9 de la division CCI 4*-S, G Star Van de Klinkenberg (Furst Romancier x Zarina), le Warmblood n\u00e9erlandais de 19 ans de Leila Saxe. Ils ont termin\u00e9 avec un r\u00e9sultat de 61,3 assorti de la huiti\u00e8me place.<\/p>\n<p>Karl Slezak (Tottenham, Ont.) compl\u00e9tait le top 10 avec Chevalier, qui participait \u00e0 la division quatre-\u00e9toiles pour la toute premi\u00e8re fois. Le Warmblood canadien de 11 ans de Carol Wiley et son cavalier se sont class\u00e9s dixi\u00e8mes (70,0). <\/p>\n<p><i><u>CCI 3*-L<\/u><\/i><\/p>\n<p>Quarante-quatre couples \u00e9taient en lice dans la division CCI 3*-L, dont Kendal Lehari avec son pur-sang de huit ans, Mitchell (Giant Gizmo x Skip Away), faisaient partie. Ils se sont class\u00e9s neuvi\u00e8mes. <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Kendal-Lehari-and-Mitchell-by-Xpress-Foto.jpg' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/><\/p>\n<p><i>Kendal Lehari et Mitchell<br \/><b>Source <\/b>: Xpress Foto<\/i><\/p>\n<p>Ayant re\u00e7u une note de 31,5 (22e place) en dressage, ils n\u2019ont d\u00e9plor\u00e9 aucune p\u00e9nalit\u00e9 de temps en cross-country, ce qui leur a permis de remonter jusqu\u2019\u00e0 la onzi\u00e8me place. Une barre d\u00e9log\u00e9e en saut d\u2019obstacles ayant ajout\u00e9 quatre fautes, le couple a affich\u00e9 un r\u00e9sultat de 35,5. <\/p>\n<p>\u00ab Le Canada a \u00e9t\u00e9 fortement repr\u00e9sent\u00e9 \u00e0 Ocala. Certains athl\u00e8tes ont v\u00e9cu leur premi\u00e8re exp\u00e9rience \u00e0 ce niveau de fa\u00e7on r\u00e9ussie, tandis que d\u2019autres ont d\u00e9montr\u00e9 de l\u2019am\u00e9lioration depuis la derni\u00e8re fois \u00bb, a d\u00e9clar\u00e9 Rebecca Howard, la chef d\u2019\u00e9quipe en concours complet. \u00ab J\u2019ai tr\u00e8s h\u00e2te au Kentucky, o\u00f9 je pourrai voir et soutenir les athl\u00e8tes en personne. \u00bb<\/p>\n<p>Les athl\u00e8tes de concours complet se pr\u00e9parent \u00e0 participer au <a href=\"https:\/\/www.kentuckythreedayevent.com\/\" target=\"_blank\" rel=\"noopener\">Land Rover Three-Day Event<\/a> (en anglais) qui se tiendra le week-end prochain (27 au 30 avril). Il s\u2019agit de l\u2019un des concours complets cinq-\u00e9toiles les plus importants au monde en raison de son niveau sup\u00e9rieur.<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Voltige.jpg' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/>Averill Saunders remporte une deuxi\u00e8me place au concours de voltige CVI 3* de Grote-Brogel<\/p>\n<p>La voltigeuse canadienne Averill Saunders (Sundre, Alb.), qui s\u2019entraine et r\u00e9side actuellement en Allemagne, a r\u00e9ussi \u00e0 se hisser \u00e0 la deuxi\u00e8me place de l\u2019\u00e9preuve de qualification pour la Coupe du monde de voltige CVI 3* pr\u00e9sent\u00e9e \u00e0 Grote-Brogel en Belgique du 21 au 23 avril dernier.<\/p>\n<p>Averill \u00e9tait associ\u00e9e \u00e0 sa longeuse, Nina Vorberg, ainsi qu\u2019\u00e0 son partenaire des Championnats du monde FEI, Rockemotion (Rockwell 3 x Di Versace), le Westphalien de 15 ans de Hans-Peter et Marlies Krukenburg, et de Kai et Nina Vorberg.<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Averill Saunders.png' alt='Weekend Highlights April 21-23: Canadians in Florida and Belgium' \/><\/p>\n<p><i>Averill Saunders descend de Rockemotion<\/i><br \/>&nbsp;<br \/>Pour les mouvements impos\u00e9s, elle a obtenu une note exceptionnelle de 8,441, ce qui lui a donn\u00e9 la premi\u00e8re position parmi les 20 repr\u00e9sentantes de sept pays. Elle a r\u00e9alis\u00e9 une autre excellente performance lors de la partie technique (8,216), pour se maintenir \u00e0 la premi\u00e8re place au terme de la seconde phase. Sa reprise libre a toutefois \u00e9t\u00e9 \u00e9maill\u00e9e de quelques malheureuses fautes, ce qui s\u2019est refl\u00e9t\u00e9 dans sa note de 7,916 ainsi que dans son r\u00e9sultat combin\u00e9 (8,191). La voltigeuse canadienne de 19 ans s\u2019est class\u00e9e deuxi\u00e8me avec un r\u00e9sultat combin\u00e9 de 8,191, derri\u00e8re l\u2019Allemande Alina Ross (8,263) qui a gagn\u00e9 l\u2019\u00e9preuve avec son cheval, Baron R. <\/p>\n<p>\u00ab Je me suis malheureusement bless\u00e9e \u00e0 un pied en descendant de cheval lors de la partie technique, ce qui m\u2019a forc\u00e9e \u00e0 adapter ma reprise libre du lendemain \u00bb, a r\u00e9pondu la jeune femme lorsqu\u2019elle a \u00e9t\u00e9 questionn\u00e9e au sujet des changements apport\u00e9s \u00e0 sa reprise libre. \u00ab Bien que les notes aient refl\u00e9t\u00e9 mes limites lors de la reprise libre, je suis tellement heureuse d\u2019avoir pu montrer ce dont je suis capable de faire dans ces circonstances. Par chance, je n\u2019ai pas subi de fracture et je peux me concentrer sur le CVI Ermelo (Pays-Bas) auquel je compte participer du 5 au 7 mai. Je vais m\u2019y rendre avec Rockemotion et Nina. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une deuxi\u00e8me place pour Kendal Lehari au CCI 4*-S d\u2019Ocala Le concours complet Ocala International Festival of Eventing pr\u00e9sentait une division CCI4*-S pour la toute premi\u00e8re fois depuis ses d\u00e9buts en 2006. Ce grand rendez-vous, qui a eu lieu du 20 au 23 avril 2023 au Florida Horse Park d\u2019Ocala, en Floride, a attir\u00e9 500 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[238],"tags":[],"class_list":["post-25919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-de-haut-niveau"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"Une deuxi\u00e8me place pour Kendal Lehari au CCI 4*-S d\u2019Ocala Le concours complet Ocala International Festival of Eventing pr\u00e9sentait une division CCI4*-S pour la toute premi\u00e8re fois depuis ses d\u00e9buts en 2006. Ce grand rendez-vous, qui a eu lieu du 20 au 23 avril 2023 au Florida Horse Park d\u2019Ocala, en Floride, a attir\u00e9 500 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique\",\"datePublished\":\"2023-04-26T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/\"},\"wordCount\":1178,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg\",\"articleSection\":[\"Sport de haut niveau\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/\",\"name\":\"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg\",\"datePublished\":\"2023-04-26T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg\",\"contentUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg\",\"width\":1000,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/author\\\/mberry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/","og_locale":"fr_CA","og_type":"article","og_title":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada","og_description":"Une deuxi\u00e8me place pour Kendal Lehari au CCI 4*-S d\u2019Ocala Le concours complet Ocala International Festival of Eventing pr\u00e9sentait une division CCI4*-S pour la toute premi\u00e8re fois depuis ses d\u00e9buts en 2006. Ce grand rendez-vous, qui a eu lieu du 20 au 23 avril 2023 au Florida Horse Park d\u2019Ocala, en Floride, a attir\u00e9 500 [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/","og_site_name":"Equestrian Canada","article_published_time":"2023-04-26T00:00:00+00:00","og_image":[{"width":1000,"height":778,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique","datePublished":"2023-04-26T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/"},"wordCount":1178,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg","articleSection":["Sport de haut niveau"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/","url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/","name":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg","datePublished":"2023-04-26T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Kendal-Lehari-and-Audacious-by-Xpress-Foto.jpg","width":1000,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-21-au-23-avril-le-canada-en-floride-et-en-belgique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Faits saillants du week-end du 21 au 23 avril : Le Canada en Floride et en Belgique"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=25919"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3880"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=25919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=25919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=25919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}