{"id":25874,"date":"2023-03-01T00:00:00","date_gmt":"2023-03-01T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/"},"modified":"2023-03-01T00:00:00","modified_gmt":"2023-03-01T00:00:00","slug":"faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/","title":{"rendered":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international"},"content":{"rendered":"<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Endurance.jpg' alt='Weekend Highlights Feb 24-26: Canadians met the heat across the world' \/><\/p>\n<p>C\u2019est aux Championnats du monde d\u2019endurance Butheeb 2022 de la F\u00e9d\u00e9ration Equestre Internationale (FEI), un \u00e9v\u00e9nement o\u00f9 la compl\u00e9tion seule du parcours rel\u00e8ve de l\u2019exploit, que Robert Gielen, un Canadien de 73 ans, s\u2019est empar\u00e9 de la 41e place parmi 129 couples de 37 pays. L\u2019\u00e9preuve \u00e9tait tenue en plein d\u00e9sert d\u2019Abu Dhabi (\u00c9mirats arabes unis) le 25 f\u00e9vrier 2023.<\/p>\n<p>Cette dix-huiti\u00e8me \u00e9dition devait avoir lieu en octobre 2022 \u00e0 V\u00e9rone, en Italie, mais a \u00e9t\u00e9 repouss\u00e9e le mois pr\u00e9c\u00e9dent l\u2019\u00e9v\u00e9nement, car on s\u2019inqui\u00e9tait de la s\u00e9curit\u00e9 du site. Le processus de s\u00e9lection a repris plus tard pour prendre fin en avril 2023.<\/p>\n<p>Robert Gielen (Flesherton, Ont.) et More Bang For Your Buck (Doran x Forty Thieves), son hongre arabe de 14 ans qu\u2019il surnomme Bang, formaient l\u2019un des deux couples nord-am\u00e9ricains de la comp\u00e9tition.<\/p>\n<p>\u00ab C\u2019\u00e9tait un championnat du monde, donc tous les chevaux pr\u00e9sents \u00e9taient les meilleurs de leurs pays \u00bb, a dit le cavalier au sujet de son exp\u00e9rience. \u00ab Cela rend la comp\u00e9tition tellement unique. Il s\u2019agissait de ma quatri\u00e8me \u00e9preuve mondiale et je dois dire que chaque site comporte ses propres d\u00e9fis. Ici, c\u2019\u00e9tait le sable. Imaginez-vous en train de courir un marathon sur la plage. En Am\u00e9rique du Nord, le terrain est vari\u00e9 et est donc beaucoup plus technique qu\u2019ici. Nous devons alors nous adapter au parcours au fur et \u00e0 mesure. \u00bb<\/p>\n<p>Le parcours de 160 km, qui comportait six tours, \u00e9tait dress\u00e9 dans un paysage magnifique sur le site de calibre mondial du Butheeb International Endurance Village. Plusieurs points d\u2019eau avaient \u00e9t\u00e9 install\u00e9s afin d\u2019assurer une hydratation et un contr\u00f4le de la temp\u00e9rature ad\u00e9quats chez les concurrentes et concurrents. Durant l\u2019\u00e9preuve, les athl\u00e8tes s\u2019y arr\u00eataient pour boire, se reposer et se soumettre \u00e0 des examens m\u00e9dicaux, une \u00e9tape obligatoire alors que la temp\u00e9rature atteignait 33 degr\u00e9s Celsius durant la journ\u00e9e.<\/p>\n<p>\u00ab Il faisait d\u00e9finitivement tr\u00e8s chaud, mais ce n\u2019\u00e9tait pas particuli\u00e8rement humide \u00bb, a ajout\u00e9 M. Gielen \u00e0 propos de la chaleur. \u00ab C\u2019\u00e9tait similaire \u00e0 la Floride, mais avec moins d\u2019humidit\u00e9. Le soleil tapait moins aussi. C\u2019est la plante de mes pieds qui a le plus souffert apr\u00e8s 11,5 heures en selle! \u00bb<\/p>\n<p>L\u2019endurance \u00e9tait d\u00e9finitivement de mise durant la comp\u00e9tition. \u00ab Cela m\u2019\u00e9pate toujours de voir \u00e0 quel point les chevaux s\u2019adaptent \u00e0 ce qu\u2019on leur demande. Le niveau athl\u00e9tique de Bang m\u2019impressionne \u00bb, a expliqu\u00e9 l\u2019athl\u00e8te. \u00ab Notre objectif \u00e9tait de terminer le parcours, un peu comme un sans-faute, et de bien choisir les moments o\u00f9 on en faisait plus et o\u00f9 on en faisait moins. On peut le constater avec le fait que 43 couples sur 129 ont r\u00e9ussi \u00e0 compl\u00e9ter le parcours. \u00bb<\/p>\n<p>Le duo canadien a franchi la ligne d\u2019arriv\u00e9e juste derri\u00e8re l\u2019Am\u00e9ricaine Cheryl van Deusen et sa monture JG General. \u00ab La strat\u00e9gie repose toujours sur un \u00e9quilibre entre le confort qu\u2019un cheval ressent en troupeau et le fait que l\u2019on concourt de fa\u00e7on individuelle \u00bb, a d\u00e9crit M. Gielen. \u00ab Bang et moi nous mesurions au parcours et \u00e0 nous-m\u00eames, pas n\u00e9cessairement aux autres athl\u00e8tes. <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Bob3.jpg' alt='Weekend Highlights Feb 24-26: Canadians met the heat across the world' \/><\/p>\n<p>Les championnats, tout comme n\u2019importe quel \u00e9v\u00e9nement \u00e9questre, demeurent n\u00e9anmoins un travail d\u2019\u00e9quipe. Le cavalier tenait \u00e0 exprimer sa gratitude : \u00ab Je veux remercier mon \u00e9quipe de soutien et de grooms compos\u00e9e de Dina Riddick, Misha Green et Wendy Benns. Elles m\u2019ont aid\u00e9 \u00e0 atteindre mon but et demeurent toujours professionnelles, tout en sachant comment s\u2019amuser! \u00bb Son \u00e9quipe a \u00e9galement publi\u00e9 des mises \u00e0 jour sur les m\u00e9dias sociaux pour que son public canadien puisse le suivre dans cet \u00e9v\u00e9nement excitant.<\/p>\n<p>Apr\u00e8s cet accomplissement, M. Gielen est maintenant pr\u00eat \u00e0 passer les r\u00eanes \u00e0 la prochaine g\u00e9n\u00e9ration d\u2019endurance. \u00ab Je pense qu\u2019il s\u2019agissait de mes derniers Championnats du monde. Je suis pr\u00eat \u00e0 laisser ma place \u00e0 de plus jeunes athl\u00e8tes du Canada. Je vais continuer \u00e0 concourir \u00e0 l\u2019\u00e9chelle nationale. Quant \u00e0 Bang, il va bien entendu se reposer pendant un bon moment. Les 36 heures de d\u00e9placement, la comp\u00e9tition, le vol de retour et les 7 jours de quarantaine ne sont pas faciles. \u00bb<\/p>\n<p>Il quitte ainsi le d\u00e9sert avec grande fiert\u00e9. \u00ab Je suis venu pour r\u00e9ussir ce parcours en particulier\u2026 c\u2019est mission accomplie! Je suis tr\u00e8s fier de mon cheval, qui est le v\u00e9ritable athl\u00e8te! \u00bb<\/p>\n<p><i><b>Source <\/b>: Wendy Benns et Misha Green<\/i>&nbsp;<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Dressage.jpg' alt='Weekend Highlights Feb 24-26: Canadians met the heat across the world' \/><\/p>\n<p>Mathilde Blais-T\u00e9treault a pris la troisi\u00e8me place de la reprise libre Grand Prix du CDI3* FEI de vendredi, une \u00e9preuve tenue \u00e0 l\u2019Adequan Global Dressage Festival de Wellington, en Floride.<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Mathilde Blais.jpg' alt='Weekend Highlights Feb 24-26: Canadians met the heat across the world' \/><\/p>\n<p><i><b>Source&nbsp;<\/b>: Cealy Tetley<\/i><\/p>\n<p>La cavali\u00e8re de Montr\u00e9al (Qu\u00e9bec) et Fedor (Glock\u2019s Johnson TN x Negro), le Warmblood n\u00e9erlandais de 13 ans de Laurence Blais-T\u00e9treault, ont compl\u00e9t\u00e9 l\u2019\u00e9v\u00e9nement avec un impressionnant 71,180 %, la deuxi\u00e8me note la plus \u00e9lev\u00e9e de leur carri\u00e8re. Le couple s\u2019est ainsi log\u00e9 au troisi\u00e8me rang, juste derri\u00e8re la Tha\u00eflandaise Suphakamol Vuntanadit (71,580 %, deuxi\u00e8me place) et l\u2019Espagnol Pablo Gomez Molina (77,865 %, troisi\u00e8me place), qui ont tous deux obtenu leurs meilleurs r\u00e9sultats \u00e0 vie.<\/p>\n<p>Dans une publication r\u00e9cente sur les m\u00e9dias sociaux, la cavali\u00e8re indique : \u00ab Je suis extr\u00eamement fi\u00e8re de Fritz, qui a obtenu une troisi\u00e8me place \u00e0 sa toute premi\u00e8re reprise en nocturne, ce vendredi. \u00bb<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/SautDobstacles.jpg' alt='Weekend Highlights Feb 24-26: Canadians met the heat across the world' \/><\/p>\n<p>Tim Wilks, un cavalier canadien de saut d\u2019obstacles d\u2019Henley-on-Thames (Royaume-Uni) et Diamanthella VG Z (Diamant de Semilly x Hickory Mail) ont remport\u00e9 le Big Tour Small Grand Prix CSI 4* \u00e0 la troisi\u00e8me semaine du XXIX Andalucia Sunshine Tour \u00e0 Vejer de la Frontera (Espagne), le 25 f\u00e9vrier.<\/p>\n<p>L\u2019athl\u00e8te et la jument Zangersheide alezane de dix ans d\u2019IN Showjumpers ont d\u00e9croch\u00e9 leur premi\u00e8re victoire ensemble avec un sans-faute et un temps de 36,89 secondes. Leur performance leur a permis de surpasser l\u2019Am\u00e9ricain Michael Hughes et sa monture Kashmir van d\u2019oude Pastory, qui ont pris le deuxi\u00e8me rang (37,31 secondes).<\/p>\n<p><i><b>Photo Credit<\/b>: <a href=\"https:\/\/www.instagram.com\/equisportif\/\" target=\"_blank\" rel=\"noopener\">Equisportif<\/a><\/i><\/p>\n<p>Cette victoire \u00e9tait bien importante pour le duo, qui avait affront\u00e9 pas moins de 73 cavali\u00e8res et cavaliers. Seulement 20 couples ont pu passer au barrage pour s\u2019attaquer au parcours dessin\u00e9 par le concepteur italien Elio Travagliati. M. Wilks et Diana ont \u00e9t\u00e9 le seul couple \u00e0 le franchir en moins de 37 secondes.<\/p>\n<p>\u00ab Je suis combl\u00e9. Je suis tr\u00e8s reconnaissant envers ma superbe \u00e9quipe. Merci pour tout ce que vous faites \u00bb, a d\u00e9clar\u00e9 le cavalier de 28 ans.<\/p>\n<p>Pour en savoir plus et voir les r\u00e9sultats, veuillez cliquer <a href=\"https:\/\/www.sunshinetour.net\/en\/results\/ranking\/ayto-vejer-small-gp-145-lr\/26750763\/147273728\/224961849\" target=\"_blank\" rel=\"noopener\">ici<\/a>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est aux Championnats du monde d\u2019endurance Butheeb 2022 de la F\u00e9d\u00e9ration Equestre Internationale (FEI), un \u00e9v\u00e9nement o\u00f9 la compl\u00e9tion seule du parcours rel\u00e8ve de l\u2019exploit, que Robert Gielen, un Canadien de 73 ans, s\u2019est empar\u00e9 de la 41e place parmi 129 couples de 37 pays. L\u2019\u00e9preuve \u00e9tait tenue en plein d\u00e9sert d\u2019Abu Dhabi (\u00c9mirats arabes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[238],"tags":[],"class_list":["post-25874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-de-haut-niveau"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"C\u2019est aux Championnats du monde d\u2019endurance Butheeb 2022 de la F\u00e9d\u00e9ration Equestre Internationale (FEI), un \u00e9v\u00e9nement o\u00f9 la compl\u00e9tion seule du parcours rel\u00e8ve de l\u2019exploit, que Robert Gielen, un Canadien de 73 ans, s\u2019est empar\u00e9 de la 41e place parmi 129 couples de 37 pays. L\u2019\u00e9preuve \u00e9tait tenue en plein d\u00e9sert d\u2019Abu Dhabi (\u00c9mirats arabes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international\",\"datePublished\":\"2023-03-01T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\"},\"wordCount\":1152,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg\",\"articleSection\":[\"Sport de haut niveau\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\",\"url\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\",\"name\":\"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg\",\"datePublished\":\"2023-03-01T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage\",\"url\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg\",\"contentUrl\":\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/equestrian.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#website\",\"url\":\"https:\/\/equestrian.ca\/fr\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/equestrian.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\/\/equestrian.ca\/fr\/author\/mberry\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/","og_locale":"fr_CA","og_type":"article","og_title":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada","og_description":"C\u2019est aux Championnats du monde d\u2019endurance Butheeb 2022 de la F\u00e9d\u00e9ration Equestre Internationale (FEI), un \u00e9v\u00e9nement o\u00f9 la compl\u00e9tion seule du parcours rel\u00e8ve de l\u2019exploit, que Robert Gielen, un Canadien de 73 ans, s\u2019est empar\u00e9 de la 41e place parmi 129 couples de 37 pays. L\u2019\u00e9preuve \u00e9tait tenue en plein d\u00e9sert d\u2019Abu Dhabi (\u00c9mirats arabes [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/","og_site_name":"Equestrian Canada","article_published_time":"2023-03-01T00:00:00+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international","datePublished":"2023-03-01T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/"},"wordCount":1152,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg","articleSection":["Sport de haut niveau"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/","url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/","name":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg","datePublished":"2023-03-01T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Bob2.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-weekend-du-24-au-26-fevrier-le-canada-affronte-la-chaleur-a-linternational\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Faits saillants du weekend du 24 au 26 f\u00e9vrier : Le Canada affronte la chaleur \u00e0 l\u2019international"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=25874"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3802"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=25874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=25874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=25874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}