{"id":25741,"date":"2020-02-25T00:00:00","date_gmt":"2020-02-25T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/"},"modified":"2020-02-25T00:00:00","modified_gmt":"2020-02-25T00:00:00","slug":"lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/","title":{"rendered":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4*"},"content":{"rendered":"<p>L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pour la Coupe des Nations de la FEI 150 000 $ CSIO 4* du 29 f\u00e9vrier sera compos\u00e9e des cavaliers suivants : <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/2020 WEF Nations Cup Team Announcement_FR.png' alt='Canadian Show Jumping Team Ready to Tackle the CSIO 4* Winter Equestrian Festival' \/><\/p>\n<p>\u00ab Je crois que nous avons une \u00e9quipe tr\u00e8s solide qui repr\u00e9sentera le Canada \u00e0 la Coupe des Nations \u00e0 Wellington cette semaine \u00bb, affirme le chef d\u2019\u00e9quipe Mark Laskin qui est sur place pour appuyer le groupe canadien de saut d\u2019obstacles. \u00ab Si les cavaliers et les chevaux performent \u00e0 la hauteur de ce qu\u2019on attend d\u2019eux, nous devrions obtenir un tr\u00e8s bon r\u00e9sultat! \u00bb<\/p>\n<p>Les athl\u00e8tes canadiens suivants participeront individuellement au concours dans la division CSIO :<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/2020 WEF Nations Cup Team Announcement - Individuals_FR.png' alt='Canadian Show Jumping Team Ready to Tackle the CSIO 4* Winter Equestrian Festival' \/><\/p>\n<p>La Coupe des Nations se d\u00e9roulera \u00e0 l\u2019International Arena du Centre \u00e9questre international de Palm Beach (PBIEC), sous les r\u00e9flecteurs, \u00e0 compter de 19 h (HE). Les cat\u00e9gories de la Coupe des Nations sont les seuls types de comp\u00e9tition de saut d\u2019obstacles o\u00f9 les cavaliers concourent par \u00e9quipe de quatre et affrontent d\u2019autres pays. Pour d\u00e9terminer le pointage global d\u2019une \u00e9quipe, les trois meilleurs pointages de chaque \u00e9quipe sont comptabilis\u00e9s pour arriver au r\u00e9sultat final du concours \u00e0 deux rondes. <\/p>\n<p>Nous en sommes \u00e0 la huiti\u00e8me semaine du WEF CSIO 4*, une s\u00e9rie de comp\u00e9titions internationales de haut niveau de 12 semaines qui se d\u00e9roule chaque ann\u00e9e en Floride et qui attire les meilleurs cavaliers de partout dans le monde.<\/p>\n<p>Pour de plus amples renseignements sur le WEF CSIO 4*, visitez le site <a href=\"http:\/\/pbiec.coth.com\" target=\"_blank\" rel=\"noopener\">http:\/\/pbiec.coth.com<\/a>. <\/p>\n<p style=\"text-align: center;\">&#8211; 30 &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pour la Coupe des Nations de la FEI 150 000 $ CSIO 4* du 29 f\u00e9vrier sera compos\u00e9e des cavaliers suivants : \u00ab Je crois que nous avons une \u00e9quipe tr\u00e8s solide qui repr\u00e9sentera le Canada \u00e0 la Coupe des Nations \u00e0 Wellington cette semaine \u00bb, affirme le chef d\u2019\u00e9quipe [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[241],"tags":[],"class_list":["post-25741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anciens-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pour la Coupe des Nations de la FEI 150 000 $ CSIO 4* du 29 f\u00e9vrier sera compos\u00e9e des cavaliers suivants : \u00ab Je crois que nous avons une \u00e9quipe tr\u00e8s solide qui repr\u00e9sentera le Canada \u00e0 la Coupe des Nations \u00e0 Wellington cette semaine \u00bb, affirme le chef d\u2019\u00e9quipe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-25T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4*\",\"datePublished\":\"2020-02-25T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/\"},\"wordCount\":268,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"articleSection\":[\"Anciens articles\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/\",\"name\":\"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"datePublished\":\"2020-02-25T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"contentUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/EC_Emblem_Navy.jpg\",\"width\":800,\"height\":618},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/anciens-articles\\\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4*\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/author\\\/mberry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/","og_locale":"fr_CA","og_type":"article","og_title":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada","og_description":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pour la Coupe des Nations de la FEI 150 000 $ CSIO 4* du 29 f\u00e9vrier sera compos\u00e9e des cavaliers suivants : \u00ab Je crois que nous avons une \u00e9quipe tr\u00e8s solide qui repr\u00e9sentera le Canada \u00e0 la Coupe des Nations \u00e0 Wellington cette semaine \u00bb, affirme le chef d\u2019\u00e9quipe [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/","og_site_name":"Equestrian Canada","article_published_time":"2020-02-25T00:00:00+00:00","og_image":[{"width":800,"height":618,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4*","datePublished":"2020-02-25T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/"},"wordCount":268,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","articleSection":["Anciens articles"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/","url":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/","name":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4* - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","datePublished":"2020-02-25T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/EC_Emblem_Navy.jpg","width":800,"height":618},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/anciens-articles\/lequipe-canadienne-de-saut-dobstacles-prete-a-entrer-en-piste-au-winter-equestrian-festival-csio-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019\u00e9quipe canadienne de saut d\u2019obstacles pr\u00eate \u00e0 entrer en piste au Winter Equestrian Festival CSIO 4*"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=25741"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3404"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=25741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=25741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=25741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}