{"id":25719,"date":"2023-05-16T00:00:00","date_gmt":"2023-05-16T00:00:00","guid":{"rendered":"https:\/\/equestrian.ca\/news\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/"},"modified":"2023-05-16T00:00:00","modified_gmt":"2023-05-16T00:00:00","slug":"faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque","status":"publish","type":"post","link":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/","title":{"rendered":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que"},"content":{"rendered":"<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/ConcoursComplet.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/>Karl Slezak et Hot Bobo poursuivent sur leur lanc\u00e9e au CCI4*-L de Tryon avec une quatri\u00e8me place&nbsp;<\/p>\n<p>Karl Slezak et Hot Bobo sont visiblement encore sur leur lanc\u00e9e depuis leur victoire impressionnante au CCI4*-S du Kentucky, le 30 avril, puisqu\u2019ils se sont impos\u00e9s au quatri\u00e8me rang du CCI4*-L du Tryon Spring International, un \u00e9v\u00e9nement pr\u00e9sent\u00e9 par Fairfax &amp; Favor \u00e0 Tryon, en Caroline du Nord.<\/p>\n<p>Le duo canadien a fait preuve de chic et de pr\u00e9cision, ce qui leur a permis de conserver leur \u00e9lan et de remporter le prix du couple le mieux pr\u00e9sent\u00e9 de leur division.&nbsp;<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Karl Slezak and Hot Bobo in Tryon by Shannon Brinkman.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/><\/p>\n<p><i>Karl Slezak et Hot Bobo remportent le prix du couple le mieux pr\u00e9sent\u00e9 du CCI4*-L<br \/><b>Source <\/b>: Shannon Brinkman Photo<\/i><\/p>\n<p>Apr\u00e8s une inspection r\u00e9ussie, le cavalier de Caledon East (Ontario) et sa jument Irish Sport Horse de dix ans, Hot Bobo (VDL Arkansas x Taneys Leader), ont compl\u00e9t\u00e9 la phase de dressage avec un r\u00e9sultat de 33,0 (septi\u00e8me place). Ils se sont ensuite mesur\u00e9s au parcours de cross-country parmi 18 couples participants. <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Karl Slezak and Hot Bobo in Tryon by Shannon Brinkman1.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/><\/p>\n<p><i>Karl Slezak et Hot Bobo<br \/><b>Source <\/b>: Shannon Brinkman Photo<\/i><\/p>\n<p>Le duo a franchi le parcours comme une fl\u00e8che en seulement 10,05&nbsp;minutes, ce qui lui a permis de se hisser au quatri\u00e8me rang. Au parcours de saut d\u2019obstacles du lendemain, une cr\u00e9ation du concepteur Marc Donavan, les trois athl\u00e8tes si\u00e9geant au sommet du classement ont tous laiss\u00e9 les obstacles intacts, tandis que Karl Slezak et sa monture ont r\u00e9ussi \u00e0 conserver leur place avec une p\u00e9nalit\u00e9 (note finale de 37,0).&nbsp;  <\/p>\n<p>Pour en savoir plus sur le Tryon Spring International, veuillez cliquer <a href=\"https:\/\/www.resort.tryon.com\/events\/tryon-intl-3-day\" target=\"_blank\" rel=\"noopener\">ici<\/a> (en anglais).<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Dressage.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/>Leonie Bramall fait un retour en carri\u00e8re en Tch\u00e9quie sur Cricket BD<\/p>\n<p>Leonie Bramall, une athl\u00e8te de dressage v\u00e9t\u00e9rane du Canada, a fait son grand retour dans la carri\u00e8re apr\u00e8s une pause de seize ans. La cavali\u00e8re a port\u00e9 la feuille d\u2019\u00e9rable \u00e0 la deuxi\u00e8me \u00e9dition du CDI3* FEI (F\u00e9d\u00e9ration Equestre Internationale) de l\u2019Equine Sports Center d\u2019Olomouc, \u00e0 environ cent kilom\u00e8tres du sud-ouest d\u2019Ostrava (Tch\u00e9quie), du 11 au 14 mai.  <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Leonie Bramell.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/><\/p>\n<p><i>Leonie Bramall et Cricket BD<br \/><b>Source <\/b>: Josef Malinovsk\u00fd<\/i><\/p>\n<p>L\u2019athl\u00e8te de 59 ans, qui r\u00e9side actuellement \u00e0 Isernhagen (Allemagne) et a deux Jeux olympiques \u00e0 son actif, montait Cricket BD (Charmeur x Don Frederico), un hongre oldenburg de 11 ans qu\u2019elle a \u00e9lev\u00e9 chez elle et poss\u00e8de en copropri\u00e9t\u00e9 avec ZG Bramall-Dusche GbR. Le duo a termin\u00e9 quatri\u00e8me (66,935 %) au Grand Prix CDI3* du 12 mai.<\/p>\n<p>Le couple a livr\u00e9 une autre belle performance deux jours plus tard, en obtenant une note de 68,872 % en Grand Prix Sp\u00e9cial CDI3*. La cavali\u00e8re \u00e9tait bien satisfaite de ce r\u00e9sultat obtenu parmi neuf couples participants de sept pays. Elle a bien d\u00e9montr\u00e9 que malgr\u00e9 sa pause prolong\u00e9e du niveau Grand Prix, son exp\u00e9rience et son choix de monture avaient port\u00e9 ses fruits. <\/p>\n<p>Pour en savoir plus sur le CDI3* d\u2019Olomouc, veuillez cliquer <a href=\"https:\/\/linkprotect.cudasvc.com\/url?a=https%3a%2f%2fresults.equestrian-hub.com%2fshow%2f155543&amp;c=E,1,KIre2-LlsokQlZW6qZclXW7HiSdlPlSjcqOIPbEBfCZZIqbqlRAMiFFNxBsmAkky5alpLgrzElMOWiboqjDZ6LKblpbJ9reVxCdG6kr3ZXrl6hX8Wr-sw1X5FvnT&amp;typo=1\" target=\"_blank\" rel=\"noopener\">ici <\/a>(en anglais).<\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/SautDobstacles.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/>Ali Ramsay d\u00e9croche sa troisi\u00e8me victoire de niveau FEI au CSI3* du Kentucky Spring Classic<\/p>\n<p>Ali Ramsay et Bonita VH Keizershof Z (Bustique x For Pleasure), d\u00e9tentrices du titre de Championnes canadiennes de saut d\u2019obstacles de 2022, ont pris la palme de l\u2019\u00e9preuve en nocturne du CSI3* \u00e0 1,45 m du Kentucky Spring Horse Show de 2023, le vendredi 12 mai. <\/p>\n<p><img src='\/wp-content\/uploads\/cdn\/storage\/images_v2\/Ali Ramsay and Bonita by Shawn McMillan Photo.jpg' alt='Weekend Highlights May 12-14: Canadians in Tryon, Kentucky and the Czech Republic during Mother\u2019s Day Weekend' \/><\/p>\n<p><i>Ali Ramsay et Bonita VH Keizershof Z<br \/><b>Source <\/b>: Shawn McMillen Photography<\/i><\/p>\n<p>Un total de 54 couples ont pris le d\u00e9part de la Kentucky Spring Classic \u00e0 37 000 $ du week-end dernier. La cavali\u00e8re de Victoria (Colombie-Britannique) et sa jument Zangersheide de 12 ans \u00e9taient l\u2019un des quinze couples \u00e0 livrer un sans-faute sur le parcours strat\u00e9gique du concepteur br\u00e9silien Guilherme Jorge. Seulement neuf athl\u00e8tes ont pu passer au barrage, le temps allou\u00e9 \u00e9tant tr\u00e8s serr\u00e9 lors de cette premi\u00e8re \u00e9preuve tenue au populaire Rolex Stadium. <\/p>\n<p>Ali Ramsay et sa monture de longue date ont livr\u00e9 une performance parfaite en un temps de 42,42, ce qui leur a permis de d\u00e9crocher la troisi\u00e8me victoire de leur carri\u00e8re au niveau FEI. Le duo \u00e9tait suivi de pr\u00e8s au deuxi\u00e8me rang par la Canadienne Nicole Walker (Aurora, Ont.) et son hongre warmblood n\u00e9erlandais de 14 ans, Excellent B (Berlin x Heartbreaker), qui ont conclu le barrage en 42,57 secondes.<\/p>\n<p>Pour en savoir plus sur le Kentucky Horse Show, veuillez cliquer <a href=\"https:\/\/kentuckyhorseshows.com\/\" target=\"_blank\" rel=\"noopener\">ici <\/a>(en anglais).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Karl Slezak et Hot Bobo poursuivent sur leur lanc\u00e9e au CCI4*-L de Tryon avec une quatri\u00e8me place&nbsp; Karl Slezak et Hot Bobo sont visiblement encore sur leur lanc\u00e9e depuis leur victoire impressionnante au CCI4*-S du Kentucky, le 30 avril, puisqu\u2019ils se sont impos\u00e9s au quatri\u00e8me rang du CCI4*-L du Tryon Spring International, un \u00e9v\u00e9nement pr\u00e9sent\u00e9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[238],"tags":[],"class_list":["post-25719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-de-haut-niveau"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada\" \/>\n<meta property=\"og:description\" content=\"Karl Slezak et Hot Bobo poursuivent sur leur lanc\u00e9e au CCI4*-L de Tryon avec une quatri\u00e8me place&nbsp; Karl Slezak et Hot Bobo sont visiblement encore sur leur lanc\u00e9e depuis leur victoire impressionnante au CCI4*-S du Kentucky, le 30 avril, puisqu\u2019ils se sont impos\u00e9s au quatri\u00e8me rang du CCI4*-L du Tryon Spring International, un \u00e9v\u00e9nement pr\u00e9sent\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/\" \/>\n<meta property=\"og:site_name\" content=\"Equestrian Canada\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/\"},\"author\":{\"name\":\"Berry\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"headline\":\"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que\",\"datePublished\":\"2023-05-16T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/\"},\"wordCount\":785,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg\",\"articleSection\":[\"Sport de haut niveau\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/\",\"name\":\"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg\",\"datePublished\":\"2023-05-16T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg\",\"contentUrl\":\"https:\\\/\\\/equestrian.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg\",\"width\":2121,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/sport-de-haut-niveau\\\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/\",\"name\":\"Equestrian Canada\",\"description\":\"For the love of horses and sport for life.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/#\\\/schema\\\/person\\\/9abd3ba4d1027626b07355668e4ee3ad\",\"name\":\"Berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g\",\"caption\":\"Berry\"},\"url\":\"https:\\\/\\\/equestrian.ca\\\/fr\\\/author\\\/mberry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/","og_locale":"fr_CA","og_type":"article","og_title":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada","og_description":"Karl Slezak et Hot Bobo poursuivent sur leur lanc\u00e9e au CCI4*-L de Tryon avec une quatri\u00e8me place&nbsp; Karl Slezak et Hot Bobo sont visiblement encore sur leur lanc\u00e9e depuis leur victoire impressionnante au CCI4*-S du Kentucky, le 30 avril, puisqu\u2019ils se sont impos\u00e9s au quatri\u00e8me rang du CCI4*-L du Tryon Spring International, un \u00e9v\u00e9nement pr\u00e9sent\u00e9 [&hellip;]","og_url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/","og_site_name":"Equestrian Canada","article_published_time":"2023-05-16T00:00:00+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg","type":"image\/jpeg"}],"author":"Berry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Berry","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#article","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/"},"author":{"name":"Berry","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"headline":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que","datePublished":"2023-05-16T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/"},"wordCount":785,"commentCount":0,"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg","articleSection":["Sport de haut niveau"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/","url":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/","name":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que - Equestrian Canada","isPartOf":{"@id":"https:\/\/equestrian.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#primaryimage"},"image":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#primaryimage"},"thumbnailUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg","datePublished":"2023-05-16T00:00:00+00:00","author":{"@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad"},"breadcrumb":{"@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#primaryimage","url":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg","contentUrl":"https:\/\/equestrian.ca\/wp-content\/uploads\/2023\/09\/Karl-Slezak-and-Hot-Bobo-in-Tryon-by-Shannon-Brinkman.jpg","width":2121,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/equestrian.ca\/fr\/sport-de-haut-niveau\/faits-saillants-du-week-end-du-12-au-14-mai-les-athletes-du-canada-passent-le-week-end-de-la-fete-des-meres-a-tryon-au-kentucky-et-en-republique-tcheque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equestrian.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Faits saillants du week-end du 12 au 14 mai : Les athl\u00e8tes du Canada passent le week-end de la f\u00eate des M\u00e8res \u00e0 Tryon, au Kentucky et en R\u00e9publique tch\u00e8que"}]},{"@type":"WebSite","@id":"https:\/\/equestrian.ca\/fr\/#website","url":"https:\/\/equestrian.ca\/fr\/","name":"Equestrian Canada","description":"For the love of horses and sport for life.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equestrian.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/equestrian.ca\/fr\/#\/schema\/person\/9abd3ba4d1027626b07355668e4ee3ad","name":"Berry","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/882da3b67056b0c608086d3c77de46948b64244a4c249e81e0bf04a8095ce320?s=96&d=mm&r=g","caption":"Berry"},"url":"https:\/\/equestrian.ca\/fr\/author\/mberry\/"}]}},"_links":{"self":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/comments?post=25719"}],"version-history":[{"count":0,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/posts\/25719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media\/3539"}],"wp:attachment":[{"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/media?parent=25719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/categories?post=25719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equestrian.ca\/fr\/wp-json\/wp\/v2\/tags?post=25719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}